{"id":2014,"count":1,"description":"","link":"https:\/\/qiraatafrican.com\/fr\/tag\/affaire-de-lethiopie-somaliland\/","name":"Affaire de l'\u00c9thiopie-Somaliland","slug":"affaire-de-lethiopie-somaliland","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/qiraatafrican.com\/fr\/wp-json\/wp\/v2\/tags\/2014","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/qiraatafrican.com\/fr\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/qiraatafrican.com\/fr\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/qiraatafrican.com\/fr\/wp-json\/wp\/v2\/posts?tags=2014"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}