{"id":18040,"date":"2026-05-13T04:48:53","date_gmt":"2026-05-13T04:48:53","guid":{"rendered":"https:\/\/qiraatafrican.com\/fr\/?p=18040"},"modified":"2026-05-13T04:48:53","modified_gmt":"2026-05-13T04:48:53","slug":"un-responsable-americain-exhorte-les-autorites-du-soudan-du-sud-a-respecter-laccord-de-paix-de-2018","status":"publish","type":"post","link":"https:\/\/qiraatafrican.com\/fr\/18040\/un-responsable-americain-exhorte-les-autorites-du-soudan-du-sud-a-respecter-laccord-de-paix-de-2018\/","title":{"rendered":"Un responsable am\u00e9ricain exhorte les autorit\u00e9s du Soudan du Sud \u00e0 respecter l&rsquo;accord de paix de 2018"},"content":{"rendered":"<p>Les tensions s&rsquo;exacerbent entre les \u00c9tats-Unis et le Soudan du Sud. Lors d&rsquo;une visite \u00e0 Juba la semaine derni\u00e8re, Nick Checker, chef du Bureau des affaires africaines du d\u00e9partement d&rsquo;\u00c9tat am\u00e9ricain, a exhort\u00e9 les autorit\u00e9s sud-soudanaises \u00e0 \u00ab prendre des mesures urgentes pour r\u00e9tablir la paix \u00bb.<\/p>\n<p>Dans un communiqu\u00e9 publi\u00e9 lundi par l&rsquo;ambassade am\u00e9ricaine, Washington a appel\u00e9 Juba \u00e0 prendre des mesures suppl\u00e9mentaires pour mettre en \u0153uvre l&rsquo;accord de paix de 2018 qui a mis fin \u00e0 la guerre civile au Soudan du Sud.<\/p>\n<p>Bien qu&rsquo;imparfait, a d\u00e9clar\u00e9 M. Checker, l&rsquo;accord \u00ab fournit le fondement de la l\u00e9gitimit\u00e9 au gouvernement de transition \u00bb.<\/p>\n<p>Les \u00c9tats-Unis ont \u00e9galement d\u00e9nonc\u00e9 la d\u00e9tention du vice-pr\u00e9sident sud-soudanais Riek Machar, rival du pr\u00e9sident Salva Kiir et chef du Mouvement populaire de lib\u00e9ration du Soudan-opposition (SPLO), principal parti d&rsquo;opposition du pays.<\/p>\n<p>M. Machar a \u00e9t\u00e9 arr\u00eat\u00e9 en mars 2025, suspendu de ses fonctions et inculp\u00e9 de trahison, de meurtre et de crimes contre l&rsquo;humanit\u00e9.<\/p>\n<p>\u00ab Il est absurde de pr\u00e9tendre qu&rsquo;un dialogue interpartis a lieu \u00bb alors que Machar est actuellement en proc\u00e8s, a d\u00e9clar\u00e9 Checker.<\/p>\n<p>Le responsable am\u00e9ricain a \u00e9galement accus\u00e9 les dirigeants du Soudan du Sud d&rsquo;exploiter la crise pour obtenir l&rsquo;aide des donateurs internationaux, tout en n&rsquo;utilisant pas les fonds publics pour le peuple soudanais et en \u00ab entravant l&rsquo;acheminement de l&rsquo;aide humanitaire vitale \u00bb.<\/p>\n<p>Les tensions restent vives au Soudan du Sud, o\u00f9 les combats font toujours rage entre les forces gouvernementales et l&rsquo;opposition, et les experts mettent en garde contre une reprise d&rsquo;une guerre ouverte.<\/p>\n<p>Ces violences ont contraint des dizaines de milliers de personnes \u00e0 fuir leurs foyers, tandis que les organisations humanitaires sont r\u00e9guli\u00e8rement attaqu\u00e9es et peinent \u00e0 fonctionner.<\/p>\n<p>Malgr\u00e9 des milliards de dollars de recettes p\u00e9troli\u00e8res et des ann\u00e9es d&rsquo;aide internationale, la situation humanitaire du pays continue de se d\u00e9t\u00e9riorer.<\/p>\n<p>Pr\u00e8s des deux tiers de la population du Soudan du Sud \u2013 environ 7,9 millions de personnes \u2013 sont aujourd&rsquo;hui confront\u00e9s \u00e0 une grave famine, selon un rapport conjoint sur la s\u00e9curit\u00e9 alimentaire publi\u00e9 en avril par le gouvernement, les Nations Unies et les organisations humanitaires.<\/p>\n<p>Le Soudan du Sud devrait organiser des \u00e9lections en d\u00e9cembre apr\u00e8s des ann\u00e9es de report, les premi\u00e8res \u00e9lections nationales depuis son ind\u00e9pendance en 2011.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les tensions s&rsquo;exacerbent entre les \u00c9tats-Unis et le Soudan du Sud. Lors d&rsquo;une visite \u00e0 Juba la semaine derni\u00e8re, Nick Checker, chef du Bureau des affaires africaines du d\u00e9partement d&rsquo;\u00c9tat am\u00e9ricain, a exhort\u00e9 les autorit\u00e9s sud-soudanaises \u00e0 \u00ab prendre des mesures urgentes pour r\u00e9tablir la paix \u00bb. Dans un communiqu\u00e9 publi\u00e9 lundi par l&rsquo;ambassade am\u00e9ricaine, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":18041,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"iawp_total_views":2,"jnews-multi-image_gallery":[],"jnews_single_post":{"subtitle":"","format":"standard","override":[{"template":"1","parallax":"1","fullscreen":"1","layout":"right-sidebar","sidebar":"default-sidebar","second_sidebar":"default-sidebar","sticky_sidebar":"1","share_position":"topbottom","share_float_style":"share-monocrhome","show_share_counter":"1","show_featured":"1","show_post_meta":"1","show_post_author_image":"1","show_post_date":"1","post_date_format":"default","post_date_format_custom":"Y\/m\/d","show_post_category":"1","show_post_reading_time":"0","post_reading_time_wpm":"300","post_calculate_word_method":"str_word_count","show_zoom_button":"0","zoom_button_out_step":"2","zoom_button_in_step":"3","show_post_tag":"1","number_popup_post":"1","show_post_related":"1","show_inline_post_related":"1"}],"image_override":[{"single_post_thumbnail_size":"crop-500","single_post_gallery_size":"crop-500"}],"trending_post_position":"meta","trending_post_label":"Trending","sponsored_post_label":"Sponsored by","disable_ad":"0"},"jnews_primary_category":[],"jnews_social_meta":[],"jnews_override_counter":{"view_counter_number":"0","share_counter_number":"0","like_counter_number":"0","dislike_counter_number":"0"},"footnotes":""},"categories":[5],"tags":[],"class_list":["post-18040","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politique-africaine"],"_links":{"self":[{"href":"https:\/\/qiraatafrican.com\/fr\/wp-json\/wp\/v2\/posts\/18040","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/qiraatafrican.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/qiraatafrican.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/qiraatafrican.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/qiraatafrican.com\/fr\/wp-json\/wp\/v2\/comments?post=18040"}],"version-history":[{"count":1,"href":"https:\/\/qiraatafrican.com\/fr\/wp-json\/wp\/v2\/posts\/18040\/revisions"}],"predecessor-version":[{"id":18042,"href":"https:\/\/qiraatafrican.com\/fr\/wp-json\/wp\/v2\/posts\/18040\/revisions\/18042"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/qiraatafrican.com\/fr\/wp-json\/wp\/v2\/media\/18041"}],"wp:attachment":[{"href":"https:\/\/qiraatafrican.com\/fr\/wp-json\/wp\/v2\/media?parent=18040"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/qiraatafrican.com\/fr\/wp-json\/wp\/v2\/categories?post=18040"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/qiraatafrican.com\/fr\/wp-json\/wp\/v2\/tags?post=18040"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}