{"id":16780,"date":"2025-11-13T07:24:31","date_gmt":"2025-11-13T07:24:31","guid":{"rendered":"https:\/\/qiraatafrican.com\/fr\/?p=16780"},"modified":"2025-11-13T07:38:51","modified_gmt":"2025-11-13T07:38:51","slug":"guerre-politique-au-senegal-entre-le-president-faye-et-le-premier-ministre-sonko","status":"publish","type":"post","link":"https:\/\/qiraatafrican.com\/fr\/16780\/guerre-politique-au-senegal-entre-le-president-faye-et-le-premier-ministre-sonko\/","title":{"rendered":"Guerre politique au S\u00e9n\u00e9gal entre le pr\u00e9sident Faye et le Premier ministre Sonko"},"content":{"rendered":"<p>Une lutte de pouvoir f\u00e9roce a \u00e9clat\u00e9 entre le pr\u00e9sident s\u00e9n\u00e9galais Bassirou Diomaye Faye et son Premier ministre Ousmane Sonko, \u00e9branlant la coalition au pouvoir et soulevant des questions fondamentales sur la v\u00e9ritable autorit\u00e9 politique.<\/p>\n<p>La crise a d\u00e9but\u00e9 mardi lorsque le pr\u00e9sident Faye a annonc\u00e9 unilat\u00e9ralement le limogeage d&rsquo;A\u00efssatou Mbodj, une alli\u00e9e cl\u00e9 de Sonko, de la t\u00eate de la coalition \u00ab Diomaye Pr\u00e9sident \u00bb qui lui a permis de remporter l&rsquo;\u00e9lection de 2024.<\/p>\n<p>Il l&rsquo;a remplac\u00e9e par sa propre coordinatrice de campagne, Aminata Tour\u00e9.<\/p>\n<p>Cette d\u00e9cision contredit directement la d\u00e9claration publique faite quelques jours plus t\u00f4t par Sonko, selon laquelle il n&rsquo;y aurait \u00ab aucun changement \u00e0 la t\u00eate de la coalition \u00bb, marquant ainsi une contestation d\u00e9lib\u00e9r\u00e9e de l&rsquo;influence du Premier ministre.<\/p>\n<p>Le parti de Sonko qualifie la d\u00e9cision du pr\u00e9sident d&rsquo;\u00ab ill\u00e9gale \u00bb.<\/p>\n<p>Dans une r\u00e9ponse rapide et ferme, Sonko a r\u00e9uni son parti Pastef, qui a publi\u00e9 un communiqu\u00e9 rejetant la l\u00e9gitimit\u00e9 du pr\u00e9sident \u00e0 effectuer un tel changement.<\/p>\n<p>Le parti a affirm\u00e9 que Faye \u00ab n&rsquo;a pas le pouvoir de destituer \u00bb Mbodj et a d\u00e9clar\u00e9 sans ambages ne partager \u00ab ni les m\u00eames valeurs ni les m\u00eames principes \u00bb avec le nouveau candidat du pr\u00e9sident, r\u00e9v\u00e9lant ainsi une profonde division id\u00e9ologique et politique au sein du gouvernement.<\/p>\n<p>Une lutte pour le pouvoir, o\u00f9 la gouvernance est en jeu.<\/p>\n<p>L&rsquo;affrontement public, men\u00e9 par le biais de communiqu\u00e9s officiels, met en lumi\u00e8re une lutte fondamentale pour le pouvoir.<\/p>\n<p>Les analystes s&rsquo;interrogent d\u00e9sormais sur la capacit\u00e9 du pr\u00e9sident Faye \u00e0 gouverner efficacement sans Sonko, qui dirige un puissant parti politique et b\u00e9n\u00e9ficie d&rsquo;une importante l\u00e9gitimit\u00e9 populaire, comme en t\u00e9moignent les milliers de partisans qu&rsquo;il a r\u00e9cemment mobilis\u00e9s.<\/p>\n<p>Cette confrontation laisse la coalition au pouvoir fractur\u00e9e et plonge le pays ouest-africain dans une p\u00e9riode de profonde incertitude politique.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Une lutte de pouvoir f\u00e9roce a \u00e9clat\u00e9 entre le pr\u00e9sident s\u00e9n\u00e9galais Bassirou Diomaye Faye et son Premier ministre Ousmane Sonko, \u00e9branlant la coalition au pouvoir et soulevant des questions fondamentales sur la v\u00e9ritable autorit\u00e9 politique. La crise a d\u00e9but\u00e9 mardi lorsque le pr\u00e9sident Faye a annonc\u00e9 unilat\u00e9ralement le limogeage d&rsquo;A\u00efssatou Mbodj, une alli\u00e9e cl\u00e9 de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":16781,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"iawp_total_views":36,"jnews-multi-image_gallery":[],"jnews_single_post":{"format":"standard","override":[{"template":"1","parallax":"1","fullscreen":"1","layout":"right-sidebar","sidebar":"default-sidebar","second_sidebar":"default-sidebar","sticky_sidebar":"1","share_position":"topbottom","share_float_style":"share-monocrhome","show_share_counter":"1","show_featured":"1","show_post_meta":"1","show_post_author_image":"1","show_post_date":"1","post_date_format":"default","post_date_format_custom":"Y\/m\/d","show_post_category":"1","show_post_reading_time":"0","post_reading_time_wpm":"300","post_calculate_word_method":"str_word_count","show_zoom_button":"0","zoom_button_out_step":"2","zoom_button_in_step":"3","show_post_tag":"1","number_popup_post":"1","show_post_related":"1","show_inline_post_related":"1"}],"image_override":[{"single_post_thumbnail_size":"crop-500","single_post_gallery_size":"crop-500"}],"trending_post_position":"meta","trending_post_label":"Trending","sponsored_post_label":"Sponsored by","disable_ad":"0","source_name":"Africa News","subtitle":""},"jnews_primary_category":[],"jnews_social_meta":[],"jnews_override_counter":{"view_counter_number":"0","share_counter_number":"0","like_counter_number":"0","dislike_counter_number":"0"},"footnotes":""},"categories":[44,5],"tags":[],"class_list":["post-16780","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-afrique-de-louest","category-politique-africaine"],"_links":{"self":[{"href":"https:\/\/qiraatafrican.com\/fr\/wp-json\/wp\/v2\/posts\/16780","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/qiraatafrican.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/qiraatafrican.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/qiraatafrican.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/qiraatafrican.com\/fr\/wp-json\/wp\/v2\/comments?post=16780"}],"version-history":[{"count":0,"href":"https:\/\/qiraatafrican.com\/fr\/wp-json\/wp\/v2\/posts\/16780\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/qiraatafrican.com\/fr\/wp-json\/wp\/v2\/media\/16781"}],"wp:attachment":[{"href":"https:\/\/qiraatafrican.com\/fr\/wp-json\/wp\/v2\/media?parent=16780"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/qiraatafrican.com\/fr\/wp-json\/wp\/v2\/categories?post=16780"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/qiraatafrican.com\/fr\/wp-json\/wp\/v2\/tags?post=16780"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}